{"id":1081,"date":"2024-04-12T14:59:30","date_gmt":"2024-04-12T12:59:30","guid":{"rendered":"https:\/\/cynthialeveneur.com\/?page_id=1081"},"modified":"2025-01-29T13:14:57","modified_gmt":"2025-01-29T12:14:57","slug":"cynthia-leveneur-realisations-illustration","status":"publish","type":"page","link":"https:\/\/cynthialeveneur.com\/index.php\/cynthia-leveneur-realisations-illustration\/","title":{"rendered":"R\u00e9alisations"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1081\" class=\"elementor elementor-1081\">\n\t\t\t\t<div class=\"elementor-element elementor-element-45e3f36 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"45e3f36\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ccdf220 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"ccdf220\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-716755f elementor-widget elementor-widget-heading\" data-id=\"716755f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Mes r\u00e9alisations<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df12f0c elementor-widget elementor-widget-heading\" data-id=\"df12f0c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">GRAPHISME & ILLUSTRATION<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-35f475e e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"35f475e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-15ecf26 elementor-widget elementor-widget-heading\" data-id=\"15ecf26\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">R\u00c9ALISATIONS PROFESSIONNELLES<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ebec483 elementor-widget elementor-widget-text-editor\" data-id=\"ebec483\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>D\u00e9couvrez mes r\u00e9alisations :<\/strong><br \/>identit\u00e9s visuelles, illustrations \u00e9ditoriales\/textiles\/branding et portraits personnalis\u00e9s.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-21aff116 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"21aff116\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e6dace elementor-widget elementor-widget-shortcode\" data-id=\"2e6dace\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"vp-portfolio vp-uid-5b144b50 vp-id-1056 \"\n\tdata-vp-layout=\"tiles\" data-vp-content-source=\"post-based\" data-vp-items-style=\"emerge\" data-vp-items-click-action=\"url\" data-vp-items-gap=\"15\" data-vp-items-gap-vertical=\"\" data-vp-pagination=\"load-more\" data-vp-next-page-url=\"\" data-vp-tiles-type=\"3|1,1|\" >\n\t<div class=\"vp-portfolio__preloader-wrap\">\n\t\t<div class=\"vp-portfolio__preloader\">\n\t\t\t<img decoding=\"async\" loading=\"eager\" src=\"https:\/\/cynthialeveneur.com\/wp-content\/plugins\/visual-portfolio\/assets\/images\/logo-dark.svg\" alt=\"Visual Portfolio, Posts &amp; Image Gallery for WordPress\" width=\"20\" height=\"20\" data-skip-lazy>\n\t\t<\/div>\n\t<\/div>\n\t\t<div class=\"vp-portfolio__layout-elements vp-portfolio__layout-elements-top vp-portfolio__layout-elements-align-center\">\n\t\t\t\t<div class=\"vp-portfolio__filter-wrap\">\n\t\t\n<div class=\"vp-filter vp-filter__style-dropdown\">\n\t<select>\n\t\t\t\t\t<option class=\"vp-filter__item vp-filter__item-active\" data-vp-url=\"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages\/1081\" data-vp-filter=\"*\" value=\"*\"  selected='selected'>\n\t\t\t\tTous les projets\n\t\t\t\t\t\t\t<\/option>\n\t\t\t\t\t\t<option class=\"vp-filter__item\" data-vp-url=\"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages\/1081?vp_filter=portfolio_category%3Aaffiches\" data-vp-filter=\"affiches\" value=\"affiches\" >\n\t\t\t\tAffiches\n\t\t\t\t\t\t\t<\/option>\n\t\t\t\t\t\t<option class=\"vp-filter__item\" data-vp-url=\"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages\/1081?vp_filter=portfolio_category%3Aidentite-visuelle\" data-vp-filter=\"identite-visuelle\" value=\"identite-visuelle\" >\n\t\t\t\tIdentit\u00e9 visuelle\n\t\t\t\t\t\t\t<\/option>\n\t\t\t\t\t\t<option class=\"vp-filter__item\" data-vp-url=\"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages\/1081?vp_filter=portfolio_category%3Aillustration-branding\" data-vp-filter=\"illustration-branding\" value=\"illustration-branding\" >\n\t\t\t\tIllustration Branding\n\t\t\t\t\t\t\t<\/option>\n\t\t\t\t\t\t<option class=\"vp-filter__item\" data-vp-url=\"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages\/1081?vp_filter=portfolio_category%3Aillustration-editoriale\" data-vp-filter=\"illustration-editoriale\" value=\"illustration-editoriale\" >\n\t\t\t\tIllustration \u00c9ditoriale\n\t\t\t\t\t\t\t<\/option>\n\t\t\t\t\t\t<option class=\"vp-filter__item\" data-vp-url=\"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages\/1081?vp_filter=portfolio_category%3Aillustration-textile\" data-vp-filter=\"illustration-textile\" value=\"illustration-textile\" >\n\t\t\t\tIllustration Textile\n\t\t\t\t\t\t\t<\/option>\n\t\t\t\t\t\t<option class=\"vp-filter__item\" data-vp-url=\"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages\/1081?vp_filter=portfolio_category%3Aportrait\" data-vp-filter=\"portrait\" value=\"portrait\" >\n\t\t\t\tPortrait\n\t\t\t\t\t\t\t<\/option>\n\t\t\t\t<\/select>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vp-portfolio__items-wrap\">\n\t\t\t\n<div class=\"vp-portfolio__items vp-portfolio__items-style-emerge vp-portfolio__items-show-overlay-hover vp-portfolio__items-show-caption-hover\">\n\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-3996 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio_category-illustration-editoriale vp-portfolio__item-uid-63199acb\" data-vp-filter=\"illustration-editoriale\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-the-bear-hunt\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\t\n\t\t<noscript><img fetchpriority=\"high\" decoding=\"async\" width=\"1067\" height=\"1067\" data-skip-lazy src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-chasse-ours.jpg\" class=\"wp-image-3997\" alt=\"\" srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-chasse-ours.jpg 1067w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-chasse-ours-300x300.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-chasse-ours-1024x1024.jpg 1024w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-chasse-ours-150x150.jpg 150w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-chasse-ours-768x768.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-chasse-ours-500x500.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-chasse-ours-800x800.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-chasse-ours-600x600.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-chasse-ours-100x100.jpg 100w\" sizes=\"(max-width: 1067px) 100vw, 1067px\" \/><\/noscript><img decoding=\"async\" width=\"1067\" height=\"1067\" src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-chasse-ours.jpg\" class=\"wp-image-3997 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMTA2NyIgaGVpZ2h0PSIxMDY3IiB2aWV3Qm94PSIwIDAgMTA2NyAxMDY3IiBmaWxsPSJub25lIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-chasse-ours.jpg\" data-srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-chasse-ours.jpg 1067w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-chasse-ours-300x300.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-chasse-ours-1024x1024.jpg 1024w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-chasse-ours-150x150.jpg 150w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-chasse-ours-768x768.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-chasse-ours-500x500.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-chasse-ours-800x800.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-chasse-ours-600x600.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-chasse-ours-100x100.jpg 100w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages\/1081?vp_filter=portfolio_category%3Aillustration-editoriale\"\n\t\t\t>\n\tIllustration \u00c9ditoriale<\/a>\t\t<\/div>\n\t\t<\/div>\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-the-bear-hunt\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\tThe Bear Hunt<\/a><\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-3981 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio_category-illustration-editoriale vp-portfolio__item-uid-e4663e29\" data-vp-filter=\"illustration-editoriale\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-mes-parents-ce-couple-de-champions\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\t\n\t\t<noscript><img decoding=\"async\" width=\"1067\" height=\"1067\" data-skip-lazy src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions.jpg\" class=\"wp-image-3982\" alt=\"\" srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions.jpg 1067w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-300x300.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-1024x1024.jpg 1024w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-150x150.jpg 150w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-768x768.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-500x500.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-800x800.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-600x600.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-100x100.jpg 100w\" sizes=\"(max-width: 1067px) 100vw, 1067px\" \/><\/noscript><img decoding=\"async\" width=\"1067\" height=\"1067\" src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions.jpg\" class=\"wp-image-3982 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMTA2NyIgaGVpZ2h0PSIxMDY3IiB2aWV3Qm94PSIwIDAgMTA2NyAxMDY3IiBmaWxsPSJub25lIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions.jpg\" data-srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions.jpg 1067w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-300x300.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-1024x1024.jpg 1024w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-150x150.jpg 150w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-768x768.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-500x500.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-800x800.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-600x600.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-100x100.jpg 100w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages\/1081?vp_filter=portfolio_category%3Aillustration-editoriale\"\n\t\t\t>\n\tIllustration \u00c9ditoriale<\/a>\t\t<\/div>\n\t\t<\/div>\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-mes-parents-ce-couple-de-champions\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\tMes parents, ce couple de champions<\/a><\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-3974 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio_category-illustration-editoriale vp-portfolio__item-uid-1394d669\" data-vp-filter=\"illustration-editoriale\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-la-foret-endormie\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\t\n\t\t<noscript><img decoding=\"async\" width=\"1067\" height=\"1067\" data-skip-lazy src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-foret-2.jpg\" class=\"wp-image-3985\" alt=\"\" srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-foret-2.jpg 1067w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-foret-2-300x300.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-foret-2-1024x1024.jpg 1024w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-foret-2-150x150.jpg 150w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-foret-2-768x768.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-foret-2-500x500.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-foret-2-800x800.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-foret-2-600x600.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-foret-2-100x100.jpg 100w\" sizes=\"(max-width: 1067px) 100vw, 1067px\" \/><\/noscript><img decoding=\"async\" width=\"1067\" height=\"1067\" src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-foret-2.jpg\" class=\"wp-image-3985 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMTA2NyIgaGVpZ2h0PSIxMDY3IiB2aWV3Qm94PSIwIDAgMTA2NyAxMDY3IiBmaWxsPSJub25lIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-foret-2.jpg\" data-srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-foret-2.jpg 1067w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-foret-2-300x300.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-foret-2-1024x1024.jpg 1024w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-foret-2-150x150.jpg 150w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-foret-2-768x768.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-foret-2-500x500.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-foret-2-800x800.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-foret-2-600x600.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-jeunesse-foret-2-100x100.jpg 100w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages\/1081?vp_filter=portfolio_category%3Aillustration-editoriale\"\n\t\t\t>\n\tIllustration \u00c9ditoriale<\/a>\t\t<\/div>\n\t\t<\/div>\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-la-foret-endormie\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\tLa For\u00eat endormie<\/a><\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-3657 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio_category-identite-visuelle vp-portfolio__item-uid-b3f7a26c\" data-vp-filter=\"identite-visuelle\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/logo-les-petits-figuiers\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" data-skip-lazy src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/logo-petits-figuiers-2.jpg\" class=\"wp-image-3660\" alt=\"Logo pour locations de vacances &quot;Les petits figuiers&quot; aux saintes en Guadeloupe.\" srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/logo-petits-figuiers-2.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/logo-petits-figuiers-2-300x300.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/logo-petits-figuiers-2-150x150.jpg 150w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/logo-petits-figuiers-2-768x768.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/logo-petits-figuiers-2-500x500.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/logo-petits-figuiers-2-600x600.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/logo-petits-figuiers-2-100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/noscript><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/logo-petits-figuiers-2.jpg\" class=\"wp-image-3660 vp-lazyload\" alt=\"Logo pour locations de vacances &quot;Les petits figuiers&quot; aux saintes en Guadeloupe.\" srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iODAwIiBoZWlnaHQ9IjgwMCIgdmlld0JveD0iMCAwIDgwMCA4MDAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" data-src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/logo-petits-figuiers-2.jpg\" data-srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/logo-petits-figuiers-2.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/logo-petits-figuiers-2-300x300.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/logo-petits-figuiers-2-150x150.jpg 150w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/logo-petits-figuiers-2-768x768.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/logo-petits-figuiers-2-500x500.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/logo-petits-figuiers-2-600x600.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/logo-petits-figuiers-2-100x100.jpg 100w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages\/1081?vp_filter=portfolio_category%3Aidentite-visuelle\"\n\t\t\t>\n\tIdentit\u00e9 visuelle<\/a>\t\t<\/div>\n\t\t<\/div>\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/logo-les-petits-figuiers\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\tLes petits figuiers<\/a><\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-1001 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio_category-identite-visuelle vp-portfolio__item-uid-89674725\" data-vp-filter=\"identite-visuelle\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/logo-senses-origin\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" data-skip-lazy src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-sens-origin-2-1.jpg\" class=\"wp-image-3651\" alt=\"Logo pour le salon de massage &quot;Senses Origin&quot;.\" srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-sens-origin-2-1.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-sens-origin-2-1-300x300.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-sens-origin-2-1-150x150.jpg 150w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-sens-origin-2-1-768x768.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-sens-origin-2-1-500x500.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-sens-origin-2-1-600x600.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-sens-origin-2-1-100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/noscript><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-sens-origin-2-1.jpg\" class=\"wp-image-3651 vp-lazyload\" alt=\"Logo pour le salon de massage &quot;Senses Origin&quot;.\" srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iODAwIiBoZWlnaHQ9IjgwMCIgdmlld0JveD0iMCAwIDgwMCA4MDAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" data-src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-sens-origin-2-1.jpg\" data-srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-sens-origin-2-1.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-sens-origin-2-1-300x300.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-sens-origin-2-1-150x150.jpg 150w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-sens-origin-2-1-768x768.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-sens-origin-2-1-500x500.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-sens-origin-2-1-600x600.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-sens-origin-2-1-100x100.jpg 100w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages\/1081?vp_filter=portfolio_category%3Aidentite-visuelle\"\n\t\t\t>\n\tIdentit\u00e9 visuelle<\/a>\t\t<\/div>\n\t\t<\/div>\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/logo-senses-origin\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\tSenses Origin<\/a><\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-999 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio_category-identite-visuelle vp-portfolio__item-uid-1d0be7db\" data-vp-filter=\"identite-visuelle\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/logo-serpico-excursions\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" data-skip-lazy src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-serpico-excursion-4.jpg\" class=\"wp-image-3655\" alt=\"Logo pour entreprise d&#039;excursion bateau &quot;Serpico Excursions&quot; en guadeloupe.\" srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-serpico-excursion-4.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-serpico-excursion-4-300x300.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-serpico-excursion-4-150x150.jpg 150w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-serpico-excursion-4-768x768.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-serpico-excursion-4-500x500.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-serpico-excursion-4-600x600.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-serpico-excursion-4-100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/noscript><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-serpico-excursion-4.jpg\" class=\"wp-image-3655 vp-lazyload\" alt=\"Logo pour entreprise d&#039;excursion bateau &quot;Serpico Excursions&quot; en guadeloupe.\" srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iODAwIiBoZWlnaHQ9IjgwMCIgdmlld0JveD0iMCAwIDgwMCA4MDAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" data-src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-serpico-excursion-4.jpg\" data-srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-serpico-excursion-4.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-serpico-excursion-4-300x300.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-serpico-excursion-4-150x150.jpg 150w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-serpico-excursion-4-768x768.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-serpico-excursion-4-500x500.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-serpico-excursion-4-600x600.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/logo-serpico-excursion-4-100x100.jpg 100w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages\/1081?vp_filter=portfolio_category%3Aidentite-visuelle\"\n\t\t\t>\n\tIdentit\u00e9 visuelle<\/a>\t\t<\/div>\n\t\t<\/div>\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/logo-serpico-excursions\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\tSerpico Excursions<\/a><\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-995 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio_category-affiches vp-portfolio__item-uid-14bdabf0\" data-vp-filter=\"affiches\" style=\"--vp-images__object-position: 50% 50%;\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/les-quatre-accords-tolteques\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1132\" data-skip-lazy src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-affiches-accords-tolteques-decopositive-2-1.jpg\" class=\"wp-image-3763\" alt=\"Affiche de d\u00e9coration accords tolt\u00e8ques.\" srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-affiches-accords-tolteques-decopositive-2-1.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-affiches-accords-tolteques-decopositive-2-1-212x300.jpg 212w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-affiches-accords-tolteques-decopositive-2-1-724x1024.jpg 724w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-affiches-accords-tolteques-decopositive-2-1-768x1087.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-affiches-accords-tolteques-decopositive-2-1-500x708.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-affiches-accords-tolteques-decopositive-2-1-600x849.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/noscript><img decoding=\"async\" width=\"800\" height=\"1132\" src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-affiches-accords-tolteques-decopositive-2-1.jpg\" class=\"wp-image-3763 vp-lazyload\" alt=\"Affiche de d\u00e9coration accords tolt\u00e8ques.\" srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iODAwIiBoZWlnaHQ9IjExMzIiIHZpZXdCb3g9IjAgMCA4MDAgMTEzMiIgZmlsbD0ibm9uZSIgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIj48L3N2Zz4=\" data-src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-affiches-accords-tolteques-decopositive-2-1.jpg\" data-srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-affiches-accords-tolteques-decopositive-2-1.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-affiches-accords-tolteques-decopositive-2-1-212x300.jpg 212w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-affiches-accords-tolteques-decopositive-2-1-724x1024.jpg 724w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-affiches-accords-tolteques-decopositive-2-1-768x1087.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-affiches-accords-tolteques-decopositive-2-1-500x708.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-affiches-accords-tolteques-decopositive-2-1-600x849.jpg 600w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages\/1081?vp_filter=portfolio_category%3Aaffiches\"\n\t\t\t>\n\tAffiches<\/a>\t\t<\/div>\n\t\t<\/div>\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/les-quatre-accords-tolteques\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\tLes quatre\u00a0accords tolt\u00e8ques<\/a><\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-993 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio_category-portrait vp-portfolio__item-uid-fdde0ec5\" data-vp-filter=\"portrait\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/octobre-rose\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1281\" data-skip-lazy src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/portrait-octobre-rose-femme-1920x1281.jpg\" class=\"wp-image-3771\" alt=\"Portrait d&#039;une femme noire avec des hibiscus pour octobre rose.\" srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/portrait-octobre-rose-femme-1920x1281.jpg 1920w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/portrait-octobre-rose-femme-300x200.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/portrait-octobre-rose-femme-1024x683.jpg 1024w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/portrait-octobre-rose-femme-768x512.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/portrait-octobre-rose-femme-1536x1025.jpg 1536w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/portrait-octobre-rose-femme-500x334.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/portrait-octobre-rose-femme-800x534.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/portrait-octobre-rose-femme-1280x854.jpg 1280w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/portrait-octobre-rose-femme-600x400.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/portrait-octobre-rose-femme.jpg 2000w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/noscript><img decoding=\"async\" width=\"1920\" height=\"1281\" src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/portrait-octobre-rose-femme-1920x1281.jpg\" class=\"wp-image-3771 vp-lazyload\" alt=\"Portrait d&#039;une femme noire avec des hibiscus pour octobre rose.\" srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMTkyMCIgaGVpZ2h0PSIxMjgxIiB2aWV3Qm94PSIwIDAgMTkyMCAxMjgxIiBmaWxsPSJub25lIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/portrait-octobre-rose-femme-1920x1281.jpg\" data-srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/portrait-octobre-rose-femme-1920x1281.jpg 1920w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/portrait-octobre-rose-femme-300x200.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/portrait-octobre-rose-femme-1024x683.jpg 1024w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/portrait-octobre-rose-femme-768x512.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/portrait-octobre-rose-femme-1536x1025.jpg 1536w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/portrait-octobre-rose-femme-500x334.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/portrait-octobre-rose-femme-800x534.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/portrait-octobre-rose-femme-1280x854.jpg 1280w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/portrait-octobre-rose-femme-600x400.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/portrait-octobre-rose-femme.jpg 2000w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages\/1081?vp_filter=portfolio_category%3Aportrait\"\n\t\t\t>\n\tPortrait<\/a>\t\t<\/div>\n\t\t<\/div>\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/octobre-rose\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\tOctobre rose<\/a><\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-991 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio_category-portrait vp-portfolio__item-uid-13d06fe9\" data-vp-filter=\"portrait\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/portraits-rare-beauty\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" data-skip-lazy src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/mockup-portrait3-1.jpg\" class=\"wp-image-3789\" alt=\"Portraits personnalis\u00e9s originaux encadr\u00e9s d&#039;une femme et d&#039;un homme.\" srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/mockup-portrait3-1.jpg 1000w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/mockup-portrait3-1-300x300.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/mockup-portrait3-1-150x150.jpg 150w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/mockup-portrait3-1-768x768.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/mockup-portrait3-1-500x500.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/mockup-portrait3-1-800x800.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/mockup-portrait3-1-600x600.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/mockup-portrait3-1-100x100.jpg 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/noscript><img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/mockup-portrait3-1.jpg\" class=\"wp-image-3789 vp-lazyload\" alt=\"Portraits personnalis\u00e9s originaux encadr\u00e9s d&#039;une femme et d&#039;un homme.\" srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMTAwMCIgaGVpZ2h0PSIxMDAwIiB2aWV3Qm94PSIwIDAgMTAwMCAxMDAwIiBmaWxsPSJub25lIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/mockup-portrait3-1.jpg\" data-srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/mockup-portrait3-1.jpg 1000w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/mockup-portrait3-1-300x300.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/mockup-portrait3-1-150x150.jpg 150w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/mockup-portrait3-1-768x768.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/mockup-portrait3-1-500x500.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/mockup-portrait3-1-800x800.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/mockup-portrait3-1-600x600.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/mockup-portrait3-1-100x100.jpg 100w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages\/1081?vp_filter=portfolio_category%3Aportrait\"\n\t\t\t>\n\tPortrait<\/a>\t\t<\/div>\n\t\t<\/div>\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/portraits-rare-beauty\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\tRare Beauty<\/a><\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-989 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio_category-portrait vp-portfolio__item-uid-0410d69a\" data-vp-filter=\"portrait\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-portrait-beach-more-worry-less\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"900\" data-skip-lazy src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/portrait-femme-plage-affiche.jpg\" class=\"wp-image-3623\" alt=\"Portrait personnalis\u00e9 femme \u00e0 la plage\" srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/portrait-femme-plage-affiche.jpg 636w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/portrait-femme-plage-affiche-212x300.jpg 212w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/portrait-femme-plage-affiche-500x708.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/portrait-femme-plage-affiche-600x849.jpg 600w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/noscript><img decoding=\"async\" width=\"636\" height=\"900\" src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/portrait-femme-plage-affiche.jpg\" class=\"wp-image-3623 vp-lazyload\" alt=\"Portrait personnalis\u00e9 femme \u00e0 la plage\" srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNjM2IiBoZWlnaHQ9IjkwMCIgdmlld0JveD0iMCAwIDYzNiA5MDAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" data-src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/portrait-femme-plage-affiche.jpg\" data-srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/portrait-femme-plage-affiche.jpg 636w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/portrait-femme-plage-affiche-212x300.jpg 212w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/portrait-femme-plage-affiche-500x708.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/portrait-femme-plage-affiche-600x849.jpg 600w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages\/1081?vp_filter=portfolio_category%3Aportrait\"\n\t\t\t>\n\tPortrait<\/a>\t\t<\/div>\n\t\t<\/div>\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-portrait-beach-more-worry-less\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\tBeach more, worry less<\/a><\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-987 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio_category-portrait vp-portfolio__item-uid-e3a8fb9d\" data-vp-filter=\"portrait\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/portrait-personnalise\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"900\" data-skip-lazy src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/portrait-homme-flamants-affiche.jpg\" class=\"wp-image-3621\" alt=\"Portrait personnalis\u00e9 homme et flamants roses.\" srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/portrait-homme-flamants-affiche.jpg 636w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/portrait-homme-flamants-affiche-212x300.jpg 212w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/portrait-homme-flamants-affiche-500x708.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/portrait-homme-flamants-affiche-600x849.jpg 600w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/noscript><img decoding=\"async\" width=\"636\" height=\"900\" src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/portrait-homme-flamants-affiche.jpg\" class=\"wp-image-3621 vp-lazyload\" alt=\"Portrait personnalis\u00e9 homme et flamants roses.\" srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNjM2IiBoZWlnaHQ9IjkwMCIgdmlld0JveD0iMCAwIDYzNiA5MDAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" data-src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/portrait-homme-flamants-affiche.jpg\" data-srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/portrait-homme-flamants-affiche.jpg 636w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/portrait-homme-flamants-affiche-212x300.jpg 212w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/portrait-homme-flamants-affiche-500x708.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/05\/portrait-homme-flamants-affiche-600x849.jpg 600w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages\/1081?vp_filter=portfolio_category%3Aportrait\"\n\t\t\t>\n\tPortrait<\/a>\t\t<\/div>\n\t\t<\/div>\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/portrait-personnalise\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\tHomme aux flamants<\/a><\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-985 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio_category-illustration-branding vp-portfolio__item-uid-0da69ab1\" data-vp-filter=\"illustration-branding\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-chocolat-packaging\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" data-skip-lazy src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/mockup-evasion-chocolat-packaging.jpg\" class=\"wp-image-3799\" alt=\"Packaging tablettes de chocolat avec des oiseaux et des cabosses de cacao. Un ara vert, un toucan et un flamant rose.\" srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/mockup-evasion-chocolat-packaging.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/mockup-evasion-chocolat-packaging-300x300.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/mockup-evasion-chocolat-packaging-150x150.jpg 150w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/mockup-evasion-chocolat-packaging-768x768.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/mockup-evasion-chocolat-packaging-500x500.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/mockup-evasion-chocolat-packaging-600x600.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/mockup-evasion-chocolat-packaging-100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/noscript><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/mockup-evasion-chocolat-packaging.jpg\" class=\"wp-image-3799 vp-lazyload\" alt=\"Packaging tablettes de chocolat avec des oiseaux et des cabosses de cacao. Un ara vert, un toucan et un flamant rose.\" srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iODAwIiBoZWlnaHQ9IjgwMCIgdmlld0JveD0iMCAwIDgwMCA4MDAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" data-src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/mockup-evasion-chocolat-packaging.jpg\" data-srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/mockup-evasion-chocolat-packaging.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/mockup-evasion-chocolat-packaging-300x300.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/mockup-evasion-chocolat-packaging-150x150.jpg 150w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/mockup-evasion-chocolat-packaging-768x768.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/mockup-evasion-chocolat-packaging-500x500.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/mockup-evasion-chocolat-packaging-600x600.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/mockup-evasion-chocolat-packaging-100x100.jpg 100w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages\/1081?vp_filter=portfolio_category%3Aillustration-branding\"\n\t\t\t>\n\tIllustration Branding<\/a>\t\t<\/div>\n\t\t<\/div>\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-chocolat-packaging\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\t\u00c9vasion chocolat<\/a><\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-982 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio_category-illustration-textile vp-portfolio__item-uid-93c20f12\" data-vp-filter=\"illustration-textile\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-explosion-tropicale\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" data-skip-lazy src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-textile-motif-volcan-tropical-tee-shirt-femme.jpg\" class=\"wp-image-3718\" alt=\"Illustration tropicale sur un tee-shirt femme.\" srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-textile-motif-volcan-tropical-tee-shirt-femme.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-textile-motif-volcan-tropical-tee-shirt-femme-300x300.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-textile-motif-volcan-tropical-tee-shirt-femme-150x150.jpg 150w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-textile-motif-volcan-tropical-tee-shirt-femme-768x768.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-textile-motif-volcan-tropical-tee-shirt-femme-500x500.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-textile-motif-volcan-tropical-tee-shirt-femme-600x600.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-textile-motif-volcan-tropical-tee-shirt-femme-100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/noscript><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-textile-motif-volcan-tropical-tee-shirt-femme.jpg\" class=\"wp-image-3718 vp-lazyload\" alt=\"Illustration tropicale sur un tee-shirt femme.\" srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iODAwIiBoZWlnaHQ9IjgwMCIgdmlld0JveD0iMCAwIDgwMCA4MDAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" data-src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-textile-motif-volcan-tropical-tee-shirt-femme.jpg\" data-srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-textile-motif-volcan-tropical-tee-shirt-femme.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-textile-motif-volcan-tropical-tee-shirt-femme-300x300.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-textile-motif-volcan-tropical-tee-shirt-femme-150x150.jpg 150w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-textile-motif-volcan-tropical-tee-shirt-femme-768x768.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-textile-motif-volcan-tropical-tee-shirt-femme-500x500.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-textile-motif-volcan-tropical-tee-shirt-femme-600x600.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-textile-motif-volcan-tropical-tee-shirt-femme-100x100.jpg 100w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages\/1081?vp_filter=portfolio_category%3Aillustration-textile\"\n\t\t\t>\n\tIllustration Textile<\/a>\t\t<\/div>\n\t\t<\/div>\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-explosion-tropicale\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\tExplosion tropicale<\/a><\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-962 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio_category-illustration-editoriale vp-portfolio__item-uid-0d41229c\" data-vp-filter=\"illustration-editoriale\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/theatre-jeunesse\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" data-skip-lazy src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/illustration-jeunesse-caraibeditions.jpg\" class=\"wp-image-3727\" alt=\"Illustrations de couverture pour des livres de th\u00e9\u00e2tre jeunesse.\" srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/illustration-jeunesse-caraibeditions.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/illustration-jeunesse-caraibeditions-300x300.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/illustration-jeunesse-caraibeditions-150x150.jpg 150w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/illustration-jeunesse-caraibeditions-768x768.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/illustration-jeunesse-caraibeditions-500x500.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/illustration-jeunesse-caraibeditions-600x600.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/illustration-jeunesse-caraibeditions-100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/noscript><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/illustration-jeunesse-caraibeditions.jpg\" class=\"wp-image-3727 vp-lazyload\" alt=\"Illustrations de couverture pour des livres de th\u00e9\u00e2tre jeunesse.\" srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iODAwIiBoZWlnaHQ9IjgwMCIgdmlld0JveD0iMCAwIDgwMCA4MDAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" data-src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/illustration-jeunesse-caraibeditions.jpg\" data-srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/illustration-jeunesse-caraibeditions.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/illustration-jeunesse-caraibeditions-300x300.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/illustration-jeunesse-caraibeditions-150x150.jpg 150w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/illustration-jeunesse-caraibeditions-768x768.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/illustration-jeunesse-caraibeditions-500x500.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/illustration-jeunesse-caraibeditions-600x600.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/04\/illustration-jeunesse-caraibeditions-100x100.jpg 100w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages\/1081?vp_filter=portfolio_category%3Aillustration-editoriale\"\n\t\t\t>\n\tIllustration \u00c9ditoriale<\/a>\t\t<\/div>\n\t\t<\/div>\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/theatre-jeunesse\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\tTh\u00e9\u00e2tre Jeunesse<\/a><\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-960 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio_category-illustration-editoriale vp-portfolio__item-uid-e34f43b0\" data-vp-filter=\"illustration-editoriale\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/haikusillustration\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" data-skip-lazy src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-haikus-caraibeditions.jpg\" class=\"wp-image-3744\" alt=\"Illustration pour couverture d&#039;un recueil de ha\u00efkus. La couverture repr\u00e9sente une femme antillaise dans un d\u00e9cor japonais.\" srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-haikus-caraibeditions.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-haikus-caraibeditions-300x300.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-haikus-caraibeditions-150x150.jpg 150w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-haikus-caraibeditions-768x768.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-haikus-caraibeditions-500x500.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-haikus-caraibeditions-600x600.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-haikus-caraibeditions-100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/noscript><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-haikus-caraibeditions.jpg\" class=\"wp-image-3744 vp-lazyload\" alt=\"Illustration pour couverture d&#039;un recueil de ha\u00efkus. La couverture repr\u00e9sente une femme antillaise dans un d\u00e9cor japonais.\" srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iODAwIiBoZWlnaHQ9IjgwMCIgdmlld0JveD0iMCAwIDgwMCA4MDAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" data-src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-haikus-caraibeditions.jpg\" data-srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-haikus-caraibeditions.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-haikus-caraibeditions-300x300.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-haikus-caraibeditions-150x150.jpg 150w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-haikus-caraibeditions-768x768.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-haikus-caraibeditions-500x500.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-haikus-caraibeditions-600x600.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/06\/illustration-haikus-caraibeditions-100x100.jpg 100w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages\/1081?vp_filter=portfolio_category%3Aillustration-editoriale\"\n\t\t\t>\n\tIllustration \u00c9ditoriale<\/a>\t\t<\/div>\n\t\t<\/div>\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/haikusillustration\/\"\n\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t>\n\tHaikus des Antilles<\/a><\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"vp-portfolio__layout-elements vp-portfolio__layout-elements-bottom vp-portfolio__layout-elements-align-center\">\n\t\t\t\t<div class=\"vp-portfolio__pagination-wrap\">\n\t\t\n<div class=\"vp-pagination vp-pagination__no-more vp-pagination__style-minimal\" data-vp-pagination-type=\"load-more\">\n\t<div class=\"vp-pagination__item\">\n\t\t<a class=\"vp-pagination__load-more\" href=\"\">\n\t\t\t<span>Voir plus<\/span>\n\t\t\t<span class=\"vp-pagination__load-more-loading\"><span class=\"vp-spinner\"><\/span><span class=\"vp-screen-reader-text\"> Voir plus<\/span><\/span>\n\t\t\t<span class=\"vp-pagination__load-more-no-more\"><\/span>\n\t\t<\/a>\n\t<\/div>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ca6886c e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"ca6886c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-95d20a4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"95d20a4\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b8002ca e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"b8002ca\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cf121b6 elementor-widget elementor-widget-heading\" data-id=\"cf121b6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">R\u00c9ALISATIONS PERSONNELLES<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d098e7 elementor-widget elementor-widget-text-editor\" data-id=\"4d098e7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Passionn\u00e9e de dessin, je r\u00e9alise r\u00e9guli\u00e8rement des s\u00e9ries d&rsquo;illustrations inspir\u00e9es de la faune et de la flore.<br \/>D\u00e9couvrez mes r\u00e9alisations personnelles et mon univers po\u00e9tique sur mes <strong>r\u00e9seaux sociaux<\/strong> !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa5893f wpr-if-square-images-yes wpr-insta-feed-layout-grid elementor-widget elementor-widget-wpr-instagram-feed\" data-id=\"aa5893f\" data-element_type=\"widget\" data-settings=\"{&quot;insta_layout_select&quot;:&quot;layout-grid&quot;,&quot;columns&quot;:&quot;3&quot;}\" data-widget_type=\"wpr-instagram-feed.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n\t\t\n\t\t<div class=\"wpr-instagram-feed-cont\">\n\t\t\t\n\t\t\t<div class=\"wpr-instagram-feed wpr-layout-grid\" data-settings=\"{&quot;insta_layout_select&quot;:&quot;layout-grid&quot;,&quot;columns&quot;:&quot;3&quot;,&quot;columns_mobile&quot;:&quot;&quot;,&quot;columns_mobile_extra&quot;:&quot;&quot;,&quot;columns_tablet&quot;:&quot;&quot;,&quot;columns_tablet_extra&quot;:&quot;3&quot;,&quot;columns_laptop&quot;:&quot;3&quot;,&quot;columns_widescreen&quot;:&quot;3&quot;,&quot;gutter_hr&quot;:10,&quot;gutter_vr&quot;:10,&quot;lightbox&quot;:{&quot;selector&quot;:&quot;.wpr-insta-feed-image-wrap&quot;,&quot;iframeMaxWidth&quot;:&quot;60%&quot;,&quot;hash&quot;:false,&quot;autoplay&quot;:&quot;&quot;,&quot;pause&quot;:0,&quot;progressBar&quot;:null,&quot;counter&quot;:&quot;&quot;,&quot;controls&quot;:&quot;&quot;,&quot;getCaptionFromTitleOrAlt&quot;:&quot;&quot;,&quot;thumbnail&quot;:&quot;&quot;,&quot;showThumbByDefault&quot;:&quot;&quot;,&quot;share&quot;:&quot;&quot;,&quot;zoom&quot;:&quot;&quot;,&quot;fullScreen&quot;:&quot;&quot;,&quot;download&quot;:&quot;&quot;},&quot;insta_load_more_settings&quot;:{&quot;instagram_access_token&quot;:&quot;IGQWRQYlFrbW5UQlI5MWRXV2RUeDI4NEFFQlFxTXBHTjJpcFNnQ0RiYWpzMnk1Nmx3Y1YxWU15OUVLVjA0V0NsYUNNVmtpZAktZAdHhoQTJjaGxiWGtBSTNFdW03WVBlcHdtN3o5QVgwTzJ1SmhGdVhuRzY0OGZA3VFEZD&quot;,&quot;limit&quot;:3,&quot;limit_mobile&quot;:3,&quot;is_mobile&quot;:&quot;other&quot;,&quot;open_in_new_tab&quot;:&quot;yes&quot;,&quot;overlay_post_link&quot;:&quot;yes&quot;,&quot;image_effects&quot;:&quot;none&quot;,&quot;image_effects_size&quot;:&quot;none&quot;,&quot;image_effects_duration&quot;:&quot;none&quot;,&quot;overlay_animation&quot;:&quot;fade-in&quot;,&quot;overlay_animation_size&quot;:&quot;large&quot;,&quot;overlay_animation_timing&quot;:&quot;ease-default&quot;,&quot;overlay_animation_tr&quot;:&quot;yes&quot;,&quot;insta_feed_elements&quot;:[{&quot;element_select&quot;:&quot;icon&quot;,&quot;element_display&quot;:&quot;inline&quot;,&quot;element_align_hr&quot;:&quot;right&quot;,&quot;_id&quot;:&quot;c804c74&quot;,&quot;element_read_more_text&quot;:null,&quot;element_comments_text_2&quot;:null,&quot;element_comments_text_3&quot;:null,&quot;element_custom_width&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:33,&quot;sizes&quot;:[]},&quot;element_hide_year&quot;:null,&quot;element_location&quot;:&quot;below&quot;,&quot;element_align_vr&quot;:null,&quot;element_username_tag&quot;:null,&quot;element_trim_text_by&quot;:null,&quot;element_word_count&quot;:null,&quot;element_letter_count&quot;:null,&quot;element_sharing_icon_1&quot;:&quot;&quot;,&quot;element_sharing_icon_2&quot;:&quot;&quot;,&quot;element_sharing_icon_3&quot;:&quot;&quot;,&quot;element_sharing_icon_4&quot;:&quot;&quot;,&quot;element_sharing_icon_5&quot;:&quot;&quot;,&quot;element_sharing_icon_6&quot;:&quot;&quot;,&quot;element_sharing_trigger&quot;:&quot;&quot;,&quot;element_sharing_trigger_icon&quot;:&quot;&quot;,&quot;element_sharing_trigger_action&quot;:&quot;&quot;,&quot;element_sharing_trigger_direction&quot;:&quot;&quot;,&quot;element_sharing_tooltip&quot;:&quot;&quot;,&quot;element_lightbox_overlay&quot;:null,&quot;element_extra_text_pos&quot;:null,&quot;element_extra_text&quot;:null,&quot;element_extra_icon_pos&quot;:null,&quot;element_extra_icon&quot;:null,&quot;element_animation&quot;:null,&quot;element_animation_timing&quot;:null,&quot;element_animation_size&quot;:null,&quot;element_animation_tr&quot;:null,&quot;element_show_on&quot;:&quot;yes&quot;},{&quot;element_select&quot;:&quot;date&quot;,&quot;element_display&quot;:&quot;inline&quot;,&quot;_id&quot;:&quot;90336de&quot;,&quot;element_read_more_text&quot;:null,&quot;element_comments_text_2&quot;:null,&quot;element_comments_text_3&quot;:null,&quot;element_hide_year&quot;:&quot;&quot;,&quot;element_location&quot;:&quot;below&quot;,&quot;element_align_vr&quot;:null,&quot;element_align_hr&quot;:&quot;left&quot;,&quot;element_username_tag&quot;:null,&quot;element_trim_text_by&quot;:null,&quot;element_word_count&quot;:null,&quot;element_letter_count&quot;:null,&quot;element_sharing_icon_1&quot;:&quot;&quot;,&quot;element_sharing_icon_2&quot;:&quot;&quot;,&quot;element_sharing_icon_3&quot;:&quot;&quot;,&quot;element_sharing_icon_4&quot;:&quot;&quot;,&quot;element_sharing_icon_5&quot;:&quot;&quot;,&quot;element_sharing_icon_6&quot;:&quot;&quot;,&quot;element_sharing_trigger&quot;:&quot;&quot;,&quot;element_sharing_trigger_icon&quot;:&quot;&quot;,&quot;element_sharing_trigger_action&quot;:&quot;&quot;,&quot;element_sharing_trigger_direction&quot;:&quot;&quot;,&quot;element_sharing_tooltip&quot;:&quot;&quot;,&quot;element_lightbox_overlay&quot;:null,&quot;element_extra_text_pos&quot;:&quot;none&quot;,&quot;element_extra_text&quot;:null,&quot;element_extra_icon_pos&quot;:&quot;none&quot;,&quot;element_extra_icon&quot;:null,&quot;element_animation&quot;:null,&quot;element_animation_timing&quot;:null,&quot;element_animation_size&quot;:null,&quot;element_animation_tr&quot;:null,&quot;element_show_on&quot;:&quot;yes&quot;}]}}\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7c2ea8 elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"c7c2ea8\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-animation-float elementor-repeater-item-54982af\" href=\"https:\/\/www.instagram.com\/cynthia_leveneur\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-tiktok elementor-animation-float elementor-repeater-item-6d14a5c\" href=\"https:\/\/www.tiktok.com\/@cynthialeveneur\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Tiktok<\/span>\n\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-tiktok\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M448,209.91a210.06,210.06,0,0,1-122.77-39.25V349.38A162.55,162.55,0,1,1,185,188.31V278.2a74.62,74.62,0,1,0,52.23,71.18V0l88,0a121.18,121.18,0,0,0,1.86,22.17h0A122.18,122.18,0,0,0,381,102.39a121.43,121.43,0,0,0,67,20.14Z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-animation-float elementor-repeater-item-e51b3a2\" href=\"https:\/\/www.linkedin.com\/in\/cynthia-leveneur-graphiste-illustratrice\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-linkedin\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-pinterest elementor-animation-float elementor-repeater-item-91b976c\" href=\"https:\/\/www.pinterest.fr\/cleveneur\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pinterest<\/span>\n\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-pinterest\" viewBox=\"0 0 496 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M496 256c0 137-111 248-248 248-25.6 0-50.2-3.9-73.4-11.1 10.1-16.5 25.2-43.5 30.8-65 3-11.6 15.4-59 15.4-59 8.1 15.4 31.7 28.5 56.8 28.5 74.8 0 128.7-68.8 128.7-154.3 0-81.9-66.9-143.2-152.9-143.2-107 0-163.9 71.8-163.9 150.1 0 36.4 19.4 81.7 50.3 96.1 4.7 2.2 7.2 1.2 8.3-3.3.8-3.4 5-20.3 6.9-28.1.6-2.5.3-4.7-1.7-7.1-10.1-12.5-18.3-35.3-18.3-56.6 0-54.7 41.4-107.6 112-107.6 60.9 0 103.6 41.5 103.6 100.9 0 67.1-33.9 113.6-78 113.6-24.3 0-42.6-20.1-36.7-44.8 7-29.5 20.5-61.3 20.5-82.6 0-19-10.2-34.9-31.4-34.9-24.9 0-44.9 25.7-44.9 60.2 0 22 7.4 36.8 7.4 36.8s-24.5 103.8-29 123.2c-5 21.4-3 51.6-.9 71.2C65.4 450.9 0 361.1 0 256 0 119 111 8 248 8s248 111 248 248z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0006a51 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"0006a51\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8bcc6e7 elementor-widget elementor-widget-text-editor\" data-id=\"8bcc6e7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Quelques-unes de mes illustrations sont <strong>disponibles \u00e0 la vente<\/strong> aux formats affiches et\/ou stickers.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28dc8cf elementor-widget elementor-widget-text-editor\" data-id=\"28dc8cf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">N&rsquo;h\u00e9sitez pas \u00e0 explorer ma boutique en ligne !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47ae01c elementor-align-center elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"47ae01c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/cynthialeveneur.com\/index.php\/shopengine-template\/boutique-test\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir les produits<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Mes r\u00e9alisations GRAPHISME &#038; ILLUSTRATION R\u00c9ALISATIONS PROFESSIONNELLES D\u00e9couvrez mes r\u00e9alisations :identit\u00e9s visuelles, illustrations \u00e9ditoriales\/textiles\/branding et portraits personnalis\u00e9s. R\u00c9ALISATIONS PERSONNELLES Passionn\u00e9e de dessin, je r\u00e9alise r\u00e9guli\u00e8rement des s\u00e9ries d&rsquo;illustrations inspir\u00e9es de la faune et de la flore.D\u00e9couvrez mes r\u00e9alisations personnelles et mon univers po\u00e9tique sur mes r\u00e9seaux sociaux ! 22 June 2022 3 June 2022 29 May 2022 Instagram Tiktok Linkedin Pinterest Quelques-unes de mes illustrations sont disponibles \u00e0 la vente aux formats affiches et\/ou stickers. N&rsquo;h\u00e9sitez pas \u00e0 explorer ma boutique en ligne ! Voir les produits<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"class_list":["post-1081","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>R\u00e9alisations illustration - Cynthia Leveneur<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez mes r\u00e9alisations : identit\u00e9s visuelles, illustrations \u00e9ditoriales\/textiles\/branding et portraits personnalis\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cynthialeveneur.com\/index.php\/cynthia-leveneur-realisations-illustration\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9alisations illustration - Cynthia Leveneur\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez mes r\u00e9alisations : identit\u00e9s visuelles, illustrations \u00e9ditoriales\/textiles\/branding et portraits personnalis\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cynthialeveneur.com\/index.php\/cynthia-leveneur-realisations-illustration\/\" \/>\n<meta property=\"og:site_name\" content=\"cynthialeveneur.com\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-29T12:14:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cynthialeveneur.com\/index.php\/cynthia-leveneur-realisations-illustration\/\",\"url\":\"https:\/\/cynthialeveneur.com\/index.php\/cynthia-leveneur-realisations-illustration\/\",\"name\":\"R\u00e9alisations illustration - Cynthia Leveneur\",\"isPartOf\":{\"@id\":\"https:\/\/cynthialeveneur.com\/#website\"},\"datePublished\":\"2024-04-12T12:59:30+00:00\",\"dateModified\":\"2025-01-29T12:14:57+00:00\",\"description\":\"D\u00e9couvrez mes r\u00e9alisations : identit\u00e9s visuelles, illustrations \u00e9ditoriales\/textiles\/branding et portraits personnalis\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\/\/cynthialeveneur.com\/index.php\/cynthia-leveneur-realisations-illustration\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cynthialeveneur.com\/index.php\/cynthia-leveneur-realisations-illustration\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cynthialeveneur.com\/index.php\/cynthia-leveneur-realisations-illustration\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/cynthialeveneur.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9alisations\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cynthialeveneur.com\/#website\",\"url\":\"https:\/\/cynthialeveneur.com\/\",\"name\":\"cynthialeveneur.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/cynthialeveneur.com\/#\/schema\/person\/2ef73bd530b005066323d2ce6896a716\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cynthialeveneur.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/cynthialeveneur.com\/#\/schema\/person\/2ef73bd530b005066323d2ce6896a716\",\"name\":\"cynthialeveneur.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cynthialeveneur.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/03\/CL-NEW-LOGO-12.png\",\"contentUrl\":\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/03\/CL-NEW-LOGO-12.png\",\"width\":461,\"height\":223,\"caption\":\"cynthialeveneur.com\"},\"logo\":{\"@id\":\"https:\/\/cynthialeveneur.com\/#\/schema\/person\/image\/\"},\"sameAs\":[\"http:\/\/cynthialeveneur.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9alisations illustration - Cynthia Leveneur","description":"D\u00e9couvrez mes r\u00e9alisations : identit\u00e9s visuelles, illustrations \u00e9ditoriales\/textiles\/branding et portraits personnalis\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cynthialeveneur.com\/index.php\/cynthia-leveneur-realisations-illustration\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9alisations illustration - Cynthia Leveneur","og_description":"D\u00e9couvrez mes r\u00e9alisations : identit\u00e9s visuelles, illustrations \u00e9ditoriales\/textiles\/branding et portraits personnalis\u00e9s.","og_url":"https:\/\/cynthialeveneur.com\/index.php\/cynthia-leveneur-realisations-illustration\/","og_site_name":"cynthialeveneur.com","article_modified_time":"2025-01-29T12:14:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cynthialeveneur.com\/index.php\/cynthia-leveneur-realisations-illustration\/","url":"https:\/\/cynthialeveneur.com\/index.php\/cynthia-leveneur-realisations-illustration\/","name":"R\u00e9alisations illustration - Cynthia Leveneur","isPartOf":{"@id":"https:\/\/cynthialeveneur.com\/#website"},"datePublished":"2024-04-12T12:59:30+00:00","dateModified":"2025-01-29T12:14:57+00:00","description":"D\u00e9couvrez mes r\u00e9alisations : identit\u00e9s visuelles, illustrations \u00e9ditoriales\/textiles\/branding et portraits personnalis\u00e9s.","breadcrumb":{"@id":"https:\/\/cynthialeveneur.com\/index.php\/cynthia-leveneur-realisations-illustration\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cynthialeveneur.com\/index.php\/cynthia-leveneur-realisations-illustration\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cynthialeveneur.com\/index.php\/cynthia-leveneur-realisations-illustration\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cynthialeveneur.com\/"},{"@type":"ListItem","position":2,"name":"R\u00e9alisations"}]},{"@type":"WebSite","@id":"https:\/\/cynthialeveneur.com\/#website","url":"https:\/\/cynthialeveneur.com\/","name":"cynthialeveneur.com","description":"","publisher":{"@id":"https:\/\/cynthialeveneur.com\/#\/schema\/person\/2ef73bd530b005066323d2ce6896a716"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cynthialeveneur.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/cynthialeveneur.com\/#\/schema\/person\/2ef73bd530b005066323d2ce6896a716","name":"cynthialeveneur.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cynthialeveneur.com\/#\/schema\/person\/image\/","url":"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/03\/CL-NEW-LOGO-12.png","contentUrl":"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/03\/CL-NEW-LOGO-12.png","width":461,"height":223,"caption":"cynthialeveneur.com"},"logo":{"@id":"https:\/\/cynthialeveneur.com\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/cynthialeveneur.com"]}]}},"_links":{"self":[{"href":"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages\/1081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/comments?post=1081"}],"version-history":[{"count":143,"href":"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages\/1081\/revisions"}],"predecessor-version":[{"id":3827,"href":"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/pages\/1081\/revisions\/3827"}],"wp:attachment":[{"href":"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/media?parent=1081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}