{"id":3981,"date":"2024-10-03T15:22:59","date_gmt":"2024-10-03T13:22:59","guid":{"rendered":"https:\/\/cynthialeveneur.com\/?post_type=portfolio&#038;p=3981"},"modified":"2024-10-03T16:21:54","modified_gmt":"2024-10-03T14:21:54","slug":"illustration-mes-parents-ce-couple-de-champions","status":"publish","type":"portfolio","link":"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-mes-parents-ce-couple-de-champions\/","title":{"rendered":"Mes parents, ce couple de champions"},"content":{"rendered":"\n<h4 class=\"wp-block-heading has-text-align-center\">Mes parents, ce couple de champions<\/h4>\n\n\n\n<p class=\"has-text-align-center\">Cr\u00e9ation de la couverture de \u00ab\u00a0Mes parents, ce couple de champions\u00a0\u00bb, un ouvrage \u00e9crit par Aur\u00e9lie Bambuck en hommage \u00e0 ses parents, Roger Bambuck et Ghislaine Barnay, en collaboration avec <a href=\"https:\/\/www.caraibeditions.fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">Cara\u00efb\u00e9ditions<\/a>.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Je r\u00e9alise des illustrations pour tout type de livre (roman, jeunesse, po\u00e9sie, biographie&#8230;). <br>N&rsquo;h\u00e9sitez pas \u00e0 me contacter pour plus d&rsquo;informations !<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-gallery aligncenter has-nested-images columns-default wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1067\" height=\"1067\" data-id=\"3982\" src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions.jpg\" alt=\"\" class=\"wp-image-3982\" srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions.jpg 1067w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-300x300.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-1024x1024.jpg 1024w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-150x150.jpg 150w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-768x768.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-500x500.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-800x800.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-600x600.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-100x100.jpg 100w\" sizes=\"(max-width: 1067px) 100vw, 1067px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1067\" height=\"1067\" data-id=\"3983\" src=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-dessin.jpg\" alt=\"\" class=\"wp-image-3983\" srcset=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-dessin.jpg 1067w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-dessin-300x300.jpg 300w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-dessin-1024x1024.jpg 1024w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-dessin-150x150.jpg 150w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-dessin-768x768.jpg 768w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-dessin-500x500.jpg 500w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-dessin-800x800.jpg 800w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-dessin-600x600.jpg 600w, https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions-dessin-100x100.jpg 100w\" sizes=\"(max-width: 1067px) 100vw, 1067px\" \/><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-1 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/cynthialeveneur.com\/index.php\/cynthia-leveneur-graphisme-illustration-contact\/\" style=\"background-color:#ea9023\"><strong>Contactez-moi<\/strong><\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-white-color has-black-background-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/cynthialeveneur.com\/index.php\/cynthia-leveneur-realisations-illustration\/\"><strong>Retour aux r\u00e9alisations<\/strong><\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mes parents, ce couple de champions Cr\u00e9ation de la couverture de \u00ab\u00a0Mes parents, ce couple de champions\u00a0\u00bb, un ouvrage \u00e9crit par Aur\u00e9lie Bambuck en hommage \u00e0 ses parents, Roger Bambuck et Ghislaine Barnay, en collaboration avec Cara\u00efb\u00e9ditions. Je r\u00e9alise des illustrations pour tout type de livre (roman, jeunesse, po\u00e9sie, biographie&#8230;). N&rsquo;h\u00e9sitez pas \u00e0 me contacter pour plus d&rsquo;informations !<\/p>\n","protected":false},"author":1,"featured_media":3982,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"portfolio_category":[20],"portfolio_tag":[],"class_list":["post-3981","portfolio","type-portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-illustration-editoriale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Illustration Mes parents, ce couple de champions &#8226; cynthialeveneur.com<\/title>\n<meta name=\"description\" content=\"Cr\u00e9ation de la couverture de \u00ab Mes parents, ce couple de champions \u00bb, un ouvrage \u00e9crit par Aur\u00e9lie Bambuck en hommage \u00e0 ses parents, Roger Bambuck et Ghislaine Barnay, en collaboration avec Cara\u00efb\u00e9ditions.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-mes-parents-ce-couple-de-champions\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Illustration Mes parents, ce couple de champions &#8226; cynthialeveneur.com\" \/>\n<meta property=\"og:description\" content=\"Cr\u00e9ation de la couverture de \u00ab Mes parents, ce couple de champions \u00bb, un ouvrage \u00e9crit par Aur\u00e9lie Bambuck en hommage \u00e0 ses parents, Roger Bambuck et Ghislaine Barnay, en collaboration avec Cara\u00efb\u00e9ditions.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-mes-parents-ce-couple-de-champions\/\" \/>\n<meta property=\"og:site_name\" content=\"cynthialeveneur.com\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-03T14:21:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1067\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-mes-parents-ce-couple-de-champions\/\",\"url\":\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-mes-parents-ce-couple-de-champions\/\",\"name\":\"Illustration Mes parents, ce couple de champions &#8226; cynthialeveneur.com\",\"isPartOf\":{\"@id\":\"https:\/\/cynthialeveneur.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-mes-parents-ce-couple-de-champions\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-mes-parents-ce-couple-de-champions\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions.jpg\",\"datePublished\":\"2024-10-03T13:22:59+00:00\",\"dateModified\":\"2024-10-03T14:21:54+00:00\",\"description\":\"Cr\u00e9ation de la couverture de \u00ab Mes parents, ce couple de champions \u00bb, un ouvrage \u00e9crit par Aur\u00e9lie Bambuck en hommage \u00e0 ses parents, Roger Bambuck et Ghislaine Barnay, en collaboration avec Cara\u00efb\u00e9ditions.\",\"breadcrumb\":{\"@id\":\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-mes-parents-ce-couple-de-champions\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-mes-parents-ce-couple-de-champions\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-mes-parents-ce-couple-de-champions\/#primaryimage\",\"url\":\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions.jpg\",\"contentUrl\":\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions.jpg\",\"width\":1067,\"height\":1067},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-mes-parents-ce-couple-de-champions\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/cynthialeveneur.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mes parents, ce couple de champions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cynthialeveneur.com\/#website\",\"url\":\"https:\/\/cynthialeveneur.com\/\",\"name\":\"cynthialeveneur.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/cynthialeveneur.com\/#\/schema\/person\/2ef73bd530b005066323d2ce6896a716\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cynthialeveneur.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/cynthialeveneur.com\/#\/schema\/person\/2ef73bd530b005066323d2ce6896a716\",\"name\":\"cynthialeveneur.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cynthialeveneur.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/03\/CL-NEW-LOGO-12.png\",\"contentUrl\":\"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/03\/CL-NEW-LOGO-12.png\",\"width\":461,\"height\":223,\"caption\":\"cynthialeveneur.com\"},\"logo\":{\"@id\":\"https:\/\/cynthialeveneur.com\/#\/schema\/person\/image\/\"},\"sameAs\":[\"http:\/\/cynthialeveneur.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Illustration Mes parents, ce couple de champions &#8226; cynthialeveneur.com","description":"Cr\u00e9ation de la couverture de \u00ab Mes parents, ce couple de champions \u00bb, un ouvrage \u00e9crit par Aur\u00e9lie Bambuck en hommage \u00e0 ses parents, Roger Bambuck et Ghislaine Barnay, en collaboration avec Cara\u00efb\u00e9ditions.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-mes-parents-ce-couple-de-champions\/","og_locale":"fr_FR","og_type":"article","og_title":"Illustration Mes parents, ce couple de champions &#8226; cynthialeveneur.com","og_description":"Cr\u00e9ation de la couverture de \u00ab Mes parents, ce couple de champions \u00bb, un ouvrage \u00e9crit par Aur\u00e9lie Bambuck en hommage \u00e0 ses parents, Roger Bambuck et Ghislaine Barnay, en collaboration avec Cara\u00efb\u00e9ditions.","og_url":"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-mes-parents-ce-couple-de-champions\/","og_site_name":"cynthialeveneur.com","article_modified_time":"2024-10-03T14:21:54+00:00","og_image":[{"width":1067,"height":1067,"url":"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-mes-parents-ce-couple-de-champions\/","url":"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-mes-parents-ce-couple-de-champions\/","name":"Illustration Mes parents, ce couple de champions &#8226; cynthialeveneur.com","isPartOf":{"@id":"https:\/\/cynthialeveneur.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-mes-parents-ce-couple-de-champions\/#primaryimage"},"image":{"@id":"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-mes-parents-ce-couple-de-champions\/#primaryimage"},"thumbnailUrl":"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions.jpg","datePublished":"2024-10-03T13:22:59+00:00","dateModified":"2024-10-03T14:21:54+00:00","description":"Cr\u00e9ation de la couverture de \u00ab Mes parents, ce couple de champions \u00bb, un ouvrage \u00e9crit par Aur\u00e9lie Bambuck en hommage \u00e0 ses parents, Roger Bambuck et Ghislaine Barnay, en collaboration avec Cara\u00efb\u00e9ditions.","breadcrumb":{"@id":"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-mes-parents-ce-couple-de-champions\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-mes-parents-ce-couple-de-champions\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-mes-parents-ce-couple-de-champions\/#primaryimage","url":"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions.jpg","contentUrl":"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/10\/illustration-bambuck-caraibeditions.jpg","width":1067,"height":1067},{"@type":"BreadcrumbList","@id":"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/illustration-mes-parents-ce-couple-de-champions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cynthialeveneur.com\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/cynthialeveneur.com\/index.php\/portfolio\/"},{"@type":"ListItem","position":3,"name":"Mes parents, ce couple de champions"}]},{"@type":"WebSite","@id":"https:\/\/cynthialeveneur.com\/#website","url":"https:\/\/cynthialeveneur.com\/","name":"cynthialeveneur.com","description":"","publisher":{"@id":"https:\/\/cynthialeveneur.com\/#\/schema\/person\/2ef73bd530b005066323d2ce6896a716"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cynthialeveneur.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/cynthialeveneur.com\/#\/schema\/person\/2ef73bd530b005066323d2ce6896a716","name":"cynthialeveneur.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cynthialeveneur.com\/#\/schema\/person\/image\/","url":"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/03\/CL-NEW-LOGO-12.png","contentUrl":"https:\/\/cynthialeveneur.com\/wp-content\/uploads\/2024\/03\/CL-NEW-LOGO-12.png","width":461,"height":223,"caption":"cynthialeveneur.com"},"logo":{"@id":"https:\/\/cynthialeveneur.com\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/cynthialeveneur.com"]}]}},"_links":{"self":[{"href":"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/portfolio\/3981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/comments?post=3981"}],"version-history":[{"count":1,"href":"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/portfolio\/3981\/revisions"}],"predecessor-version":[{"id":3984,"href":"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/portfolio\/3981\/revisions\/3984"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/media\/3982"}],"wp:attachment":[{"href":"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/media?parent=3981"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/portfolio_category?post=3981"},{"taxonomy":"portfolio_tag","embeddable":true,"href":"https:\/\/cynthialeveneur.com\/index.php\/wp-json\/wp\/v2\/portfolio_tag?post=3981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}